{"id":1443,"date":"2024-09-12T10:51:19","date_gmt":"2024-09-12T10:51:19","guid":{"rendered":"https:\/\/airporttelecom.outperforming.nl\/nl\/product\/esim-luxemburg\/"},"modified":"2025-08-17T18:24:41","modified_gmt":"2025-08-17T18:24:41","slug":"esim-luxembourg","status":"publish","type":"product","link":"https:\/\/airporttelecom.com\/fr\/esim\/luxembourg\/","title":{"rendered":"eSIM Luxembourg"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1073,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[16],"product_tag":[22],"class_list":["post-1443","product","type-product","status-publish","has-post-thumbnail","product_cat-esim","product_tag-esim-europe","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":{"gebied_afbeelding":867,"vlag_afbeelding":868,"provider":["BIC"],"product_synoniemen":null,"product_bestel_velden":"","product_omschrijving":"<h2>Internet mobile avec eSIM Luxembourg<\/h2>\r\nAvec l'eSIM Luxembourg illimit\u00e9e, vous pouvez utiliser l'internet mobile dans tout le Luxembourg. C'est id\u00e9al pour utiliser Internet et vous donne acc\u00e8s \u00e0 la messagerie \u00e9lectronique, \u00e0 Whatsapp, \u00e0 la navigation et \u00e0 d'autres applications Internet via des connexions 4G\/5G rapides. Choisissez un forfait illimit\u00e9 pour la dur\u00e9e dont vous aurez besoin : 7 jours, 14 jours ou 30 jours.\r\nForfaits de donn\u00e9es pour les voyages au Luxembourg\r\nLes eSIM pour le Luxembourg sont fournies avec un forfait de donn\u00e9es illimit\u00e9 de 7, 14 ou 30 jours :\r\n<h3>eSIM Luxembourg illimit\u00e9e 7 jours, 24 \u20ac,<\/h3>\r\n<h3>eSIM Luxembourg illimit\u00e9e 14 jours, 36 \u20ac,<\/h3>\r\n<h3>eSIM Luxembourg illimit\u00e9e 30 jours, 59 \u20ac,<\/h3>\r\n(*) Veuillez noter qu'une Politique d'Utilisation \u00c9quitable est en vigueur. En cas de consommation de donn\u00e9es excessive, le fournisseur se r\u00e9serve le droit de restreindre les capacit\u00e9s de la carte (e)SIM. Cette Politique d'Utilisation \u00c9quitable repose sur le principe d'un utilisateur unique par carte (e)SIM. Une utilisation qualifi\u00e9e de normale \u2014 incluant la navigation, la consultation d'e-mails, la recherche sur internet, l'\u00e9change de messages et appels via WhatsApp, ainsi que l'utilisation d'applications telles qu'Instagram et Snapchat\u2014 n'activera pas cette politique. Cependant, une utilisation intensive telle que la visualisation prolong\u00e9e de contenus sur YouTube ou TikTok, l'utilisation intensive de services de streaming (par exemple, Netflix) et la t\u00e9l\u00e9vision en ligne, particuli\u00e8rement lorsque combin\u00e9e au partage de connexion via un point d'acc\u00e8s mobile (hotspot) ou un routeur par plusieurs individus, est susceptible de contrevenir \u00e0 cette politique.\r\n\r\nLes eSIM pour le Luxembourg ont une excellente couverture nationale sur les r\u00e9seaux 4G et 5G d'AT&amp;T et de T-Mobile. Aucune inscription de l'utilisateur n'est requise au Luxembourg. \u00c0 l'arriv\u00e9e au Luxembourg, Internet commence \u00e0 fonctionner automatiquement. L'eSIM Luxembourg convient au partage de connexion et peut \u00e9galement \u00eatre utilis\u00e9e pour les hotspots et les MIFI.\r\n<h2>Whatsapp avec <span class=\"\u00ab\" lang=\"\u00ab\" xml:lang=\"\u00ab\" data-contrast=\"\u00ab\"><span class=\"\u00ab\">eSIM <\/span><\/span>Luxembourg<\/h2>\r\nTous les appels passant par Internet, comme ceux effectu\u00e9s avec Whatsapp, Skype et FaceTime, sont bien s\u00fbr \u00e9galement possibles avec les <span class=\"\u00ab\" lang=\"\u00ab\" data-contrast=\"\u00ab\"><span class=\"\u00ab\">eSIM <\/span><\/span> pour le Luxembourg. Vous utiliserez ensuite le forfait de donn\u00e9es sur la <span class=\"\u00ab\" lang=\"\u00ab\" xml:lang=\"\u00ab\" data-contrast=\"\u00ab\"><span class=\"\u00ab\" data-contrast=\"\u00ab\">eSIM<\/span><\/span>. Vous pouvez continuer \u00e0 utiliser Whatsapp \u00e0 tout moment avec vos propres contacts, groupes et chats existants. Apr\u00e8s avoir ins\u00e9r\u00e9 une <span class=\"\u00ab\" lang=\"\u00ab\" xml:lang=\"\u00ab\" data-contrast=\"\u00ab\"><span class=\"\u00ab\">eSIM <\/span><\/span> pr\u00e9pay\u00e9e, Whatsapp peut vous demander si vous souhaitez cr\u00e9er une nouvelle identit\u00e9 ou si tout doit rester tel quel. Si c'est le cas, choisissez la derni\u00e8re option et rien ne changera. Vous pourrez ensuite continuer \u00e0 envoyer des messages et \u00e0 passer des appels avec Whatsapp comme d'habitude.\r\n<h2>Couverture au Luxembourg<\/h2>\r\nLa couverture des r\u00e9seaux mobiles est g\u00e9n\u00e9ralement excellente au Luxembourg. C'est particuli\u00e8rement vrai dans les grandes villes comme Luxembourg. Dans les zones naturelles tr\u00e8s recul\u00e9es, la couverture peut \u00eatre un peu moins bonne. Sinon, la couverture est bonne dans tous les villages et villes gr\u00e2ce \u00e0 l'<span class=\"\u00ab\" lang=\"\u00ab\" xml:lang=\"\u00ab\" data-contrast=\"\u00ab\"><span class=\"\u00ab\">eSIM <\/span><\/span>pour le Luxembourg.\r\n<h2>eSIM pour le Luxembourg re\u00e7ue par e-mail<\/h2>\r\nVous recevrez l'eSIM pour le Luxembourg par e-mail. C'est tr\u00e8s rapide et cela peut se faire m\u00eame si vous \u00eates d\u00e9j\u00e0 au Luxembourg ou si vous partez \u00e0 tr\u00e8s court terme.\r\n\r\n&nbsp;","product_specificaties":"<h2>Internet avec eSIM Luxembourg<\/h2>\r\nChoisissez la dur\u00e9e exacte pendant laquelle vous aurez besoin de l'eSIM donn\u00e9es illimit\u00e9es :\r\n<h3>eSIM illimit\u00e9e Luxembourg 7 jours, 24 \u20ac,=<\/h3>\r\n<ul>\r\n \t<li>Donn\u00e9es illimit\u00e9es dans tout le Luxembourg*<\/li>\r\n \t<li>Offre group\u00e9e valable 7 jours. La recharge peut \u00eatre effectu\u00e9e via ce site Web.<\/li>\r\n<\/ul>\r\n<h3>eSIM Luxembourg illimit\u00e9e 14 jours, 36 \u20ac, =<\/h3>\r\n<ul>\r\n \t<li>Donn\u00e9es illimit\u00e9es dans tout le Luxembourg*<\/li>\r\n \t<li>Offre group\u00e9e valable 14 jours. Le rechargement peut \u00eatre effectu\u00e9 via ce site Web.<\/li>\r\n<\/ul>\r\n<h3>eSIM Luxembourg illimit\u00e9e 30 jours, 59 \u20ac, =<\/h3>\r\n<ul>\r\n \t<li>Donn\u00e9es illimit\u00e9es dans tout le Luxembourg*<\/li>\r\n \t<li>Forfait valable 30 jours. Le rechargement peut \u00eatre effectu\u00e9 via ce site Web.<\/li>\r\n<\/ul>\r\n(*) Il existe une politique d'utilisation \u00e9quitable. En cas d'utilisation extr\u00eame des donn\u00e9es, le fournisseur au Luxembourg peut limiter les capacit\u00e9s de la carte SIM.","product_handleiding":"<h2>Comment installer la carte SIM Luxembourg dans mon t\u00e9l\u00e9phone ?<\/h2>\r\nOuvrez le coulisseau sur le c\u00f4t\u00e9 du t\u00e9l\u00e9phone. Cela peut \u00eatre fait avec la goupille fournie avec le t\u00e9l\u00e9phone. Si vous ne l'avez pas, vous pouvez en fabriquer une en pliant un trombone. Les cartes SIM Airport Telecom sont \u00e9galement livr\u00e9es avec une goupille suppl\u00e9mentaire.\r\n\r\nRetirez votre propre carte SIM et conservez-la en lieu s\u00fbr ! Ins\u00e9rez maintenant la nouvelle carte SIM. Cela ne peut se faire que d'une seule mani\u00e8re. Il est possible que vous ayez un t\u00e9l\u00e9phone pouvant contenir plus d'une carte SIM. Ins\u00e9rez la nouvelle carte SIM comme une carte suppl\u00e9mentaire.\r\nPoussez la glissi\u00e8re de la carte SIM pour la remettre dans le t\u00e9l\u00e9phone. Si tout se passe bien, vous pouvez maintenant utiliser automatiquement la nouvelle carte SIM. Le t\u00e9l\u00e9phone peut vous demander de faire quelques r\u00e9glages suppl\u00e9mentaires.","product_veelgestelde_vragen":[{"vraag":"Quelle eSIM utiliser au Luxembourg ?","antwoord":"Pour un court s\u00e9jour de quelques jours, vous n'aurez probablement pas besoin d'autant de donn\u00e9es. Le forfait de donn\u00e9es de 12GB pour le Luxembourg peut alors suffire. Les applications telles que Whatsapp, Instagram et la navigation ne consomment pas beaucoup de donn\u00e9es. Si vous restez plus longtemps, il peut \u00eatre utile d'opter pour l'option Illimit\u00e9 afin de disposer de suffisamment de donn\u00e9es."},{"vraag":"O\u00f9 acheter une eSIM pour le Luxembourg ?","antwoord":"Vous pouvez acheter une eSIM pour le Luxembourg en ligne aupr\u00e8s d'Airport Telecom. Vous recevrez l'eSIM par e-mail. Il s'agit d'un code QR qui doit \u00eatre scann\u00e9 avec votre t\u00e9l\u00e9phone. Vous pouvez donc le faire m\u00eame si vous \u00eates d\u00e9j\u00e0 au Luxembourg ou si vous partez dans un d\u00e9lai tr\u00e8s court."}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.4 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>eSIM Luxembourg achat d&#039;appels et d&#039;Internet pr\u00e9pay\u00e9s (illimit\u00e9s) - Airport Telecom FR<\/title>\n<meta name=\"description\" content=\"Recherche carte pr\u00e9pay\u00e9e eSIM Luxembourg pour les appels (illimit\u00e9s) et Internet ? Accessible de mani\u00e8re optimale lors de d\u00e9placements en eSIM Europe. Maintenant en vente chez !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/airporttelecom.com\/fr\/esim\/luxembourg\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"eSIM Luxembourg\" \/>\n<meta property=\"og:description\" content=\"Recherche carte pr\u00e9pay\u00e9e eSIM Luxembourg pour les appels (illimit\u00e9s) et Internet ? Accessible de mani\u00e8re optimale lors de d\u00e9placements en eSIM Europe. Maintenant en vente chez !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/airporttelecom.com\/fr\/esim\/luxembourg\/\" \/>\n<meta property=\"og:site_name\" content=\"Airport Telecom FR\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-17T18:24:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/airporttelecom.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/07\/Simkaart-Luxemburg.png?wsr\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"316\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/esim\\\/luxembourg\\\/\",\"url\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/esim\\\/luxembourg\\\/\",\"name\":\"eSIM Luxembourg achat d'appels et d'Internet pr\u00e9pay\u00e9s (illimit\u00e9s) - Airport Telecom FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/esim\\\/luxembourg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/esim\\\/luxembourg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/07\\\/Simkaart-Luxemburg.png\",\"datePublished\":\"2024-09-12T10:51:19+00:00\",\"dateModified\":\"2025-08-17T18:24:41+00:00\",\"description\":\"Recherche carte pr\u00e9pay\u00e9e eSIM Luxembourg pour les appels (illimit\u00e9s) et Internet ? Accessible de mani\u00e8re optimale lors de d\u00e9placements en eSIM Europe. Maintenant en vente chez !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/esim\\\/luxembourg\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/esim\\\/luxembourg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/esim\\\/luxembourg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/07\\\/Simkaart-Luxemburg.png\",\"contentUrl\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/07\\\/Simkaart-Luxemburg.png\",\"width\":800,\"height\":316,\"caption\":\"Carte SIM luxembourgeoise\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/esim\\\/luxembourg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"eSIM\",\"item\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/esim\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Luxembourg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/\",\"name\":\"Airport Telecom\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/#organization\",\"name\":\"Airport Telecom\",\"url\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/06\\\/icon.png?wsr\",\"contentUrl\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/06\\\/icon.png?wsr\",\"width\":110,\"height\":110,\"caption\":\"Airport Telecom\"},\"image\":{\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"eSIM Luxembourg achat d'appels et d'Internet pr\u00e9pay\u00e9s (illimit\u00e9s) - Airport Telecom FR","description":"Recherche carte pr\u00e9pay\u00e9e eSIM Luxembourg pour les appels (illimit\u00e9s) et Internet ? Accessible de mani\u00e8re optimale lors de d\u00e9placements en eSIM Europe. Maintenant en vente chez !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/airporttelecom.com\/fr\/esim\/luxembourg\/","og_locale":"fr_FR","og_type":"article","og_title":"eSIM Luxembourg","og_description":"Recherche carte pr\u00e9pay\u00e9e eSIM Luxembourg pour les appels (illimit\u00e9s) et Internet ? Accessible de mani\u00e8re optimale lors de d\u00e9placements en eSIM Europe. Maintenant en vente chez !","og_url":"https:\/\/airporttelecom.com\/fr\/esim\/luxembourg\/","og_site_name":"Airport Telecom FR","article_modified_time":"2025-08-17T18:24:41+00:00","og_image":[{"width":800,"height":316,"url":"https:\/\/airporttelecom.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/07\/Simkaart-Luxemburg.png?wsr","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/airporttelecom.com\/fr\/esim\/luxembourg\/","url":"https:\/\/airporttelecom.com\/fr\/esim\/luxembourg\/","name":"eSIM Luxembourg achat d'appels et d'Internet pr\u00e9pay\u00e9s (illimit\u00e9s) - Airport Telecom FR","isPartOf":{"@id":"https:\/\/airporttelecom.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/airporttelecom.com\/fr\/esim\/luxembourg\/#primaryimage"},"image":{"@id":"https:\/\/airporttelecom.com\/fr\/esim\/luxembourg\/#primaryimage"},"thumbnailUrl":"https:\/\/airporttelecom.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/07\/Simkaart-Luxemburg.png","datePublished":"2024-09-12T10:51:19+00:00","dateModified":"2025-08-17T18:24:41+00:00","description":"Recherche carte pr\u00e9pay\u00e9e eSIM Luxembourg pour les appels (illimit\u00e9s) et Internet ? Accessible de mani\u00e8re optimale lors de d\u00e9placements en eSIM Europe. Maintenant en vente chez !","breadcrumb":{"@id":"https:\/\/airporttelecom.com\/fr\/esim\/luxembourg\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/airporttelecom.com\/fr\/esim\/luxembourg\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/airporttelecom.com\/fr\/esim\/luxembourg\/#primaryimage","url":"https:\/\/airporttelecom.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/07\/Simkaart-Luxemburg.png","contentUrl":"https:\/\/airporttelecom.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/07\/Simkaart-Luxemburg.png","width":800,"height":316,"caption":"Carte SIM luxembourgeoise"},{"@type":"BreadcrumbList","@id":"https:\/\/airporttelecom.com\/fr\/esim\/luxembourg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/airporttelecom.com\/fr\/"},{"@type":"ListItem","position":2,"name":"eSIM","item":"https:\/\/airporttelecom.com\/fr\/esim\/"},{"@type":"ListItem","position":3,"name":"Luxembourg"}]},{"@type":"WebSite","@id":"https:\/\/airporttelecom.com\/fr\/#website","url":"https:\/\/airporttelecom.com\/fr\/","name":"Airport Telecom","description":"","publisher":{"@id":"https:\/\/airporttelecom.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/airporttelecom.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/airporttelecom.com\/fr\/#organization","name":"Airport Telecom","url":"https:\/\/airporttelecom.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/airporttelecom.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/airporttelecom.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/icon.png?wsr","contentUrl":"https:\/\/airporttelecom.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/icon.png?wsr","width":110,"height":110,"caption":"Airport Telecom"},"image":{"@id":"https:\/\/airporttelecom.com\/fr\/#\/schema\/logo\/image\/"}}]}},"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/airporttelecom.com\/fr\/wp-json\/wp\/v2\/product\/1443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/airporttelecom.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/airporttelecom.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/airporttelecom.com\/fr\/wp-json\/wp\/v2\/comments?post=1443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/airporttelecom.com\/fr\/wp-json\/wp\/v2\/media\/1073"}],"wp:attachment":[{"href":"https:\/\/airporttelecom.com\/fr\/wp-json\/wp\/v2\/media?parent=1443"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/airporttelecom.com\/fr\/wp-json\/wp\/v2\/product_brand?post=1443"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/airporttelecom.com\/fr\/wp-json\/wp\/v2\/product_cat?post=1443"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/airporttelecom.com\/fr\/wp-json\/wp\/v2\/product_tag?post=1443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}