{"id":755,"date":"2024-07-30T09:05:23","date_gmt":"2024-07-30T09:05:23","guid":{"rendered":"https:\/\/airporttelecom.outperforming.nl\/nl\/?post_type=product&#038;p=755"},"modified":"2026-08-28T09:02:05","modified_gmt":"2026-08-28T09:02:05","slug":"carte-sim-hawai","status":"publish","type":"product","link":"https:\/\/airporttelecom.com\/fr\/carte-sim\/hawai\/","title":{"rendered":"Carte SIM Hawa\u00ef"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1157,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[17],"product_tag":[29],"class_list":["post-755","product","type-product","status-publish","has-post-thumbnail","product_cat-carte-sim","product_tag-carte-sim-australie-et-oceanie","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":{"gebied_afbeelding":846,"vlag_afbeelding":847,"provider":["THR","LYC","LIN"],"product_synoniemen":null,"product_bestel_velden":["vertrekdatum","phone"],"product_omschrijving":"<h2>Internet mobile \u00e0 Hawaii avec la carte SIM<\/h2>\r\n<span data-contrast=\"\u00ab\">Avec les cartes SIM pr\u00e9pay\u00e9es Hawaii d'Airport Telecom, vous pouvez utiliser l'Internet mobile dans tout l'\u00c9tat am\u00e9ricain d'Hawa\u00ef. Les cartes SIM offrent une excellente couverture sur les r\u00e9seaux 4G et 5G d'AT&amp;T et T-Mobile aux \u00c9tats-Unis. Vous pouvez choisir parmi une vari\u00e9t\u00e9 de forfaits de donn\u00e9es. Ces forfaits sont parfaits pour l'utilisation d'Internet et vous donnent acc\u00e8s \u00e0 la messagerie \u00e9lectronique, \u00e0 Whatsapp, \u00e0 la navigation et \u00e0 d'autres applications Internet gr\u00e2ce \u00e0 une connexion 4G\/5G rapide. <\/span>\r\n<h2><span data-contrast=\"\u00ab\">Donn\u00e9es et appels lors de voyages \u00e0 Hawaii<\/span><\/h2>\r\n<span data-contrast=\"\u00ab\">Les cartes SIM pour Hawaii sont disponibles avec un forfait de 12GB et un forfait de donn\u00e9es illimit\u00e9. <\/span>\r\n<h2><span data-contrast=\"\u00ab\">Whatsapp avec la carte SIM pour Hawaii<\/span><\/h2>\r\n<span data-contrast=\"\u00ab\">Tous les appels pass\u00e9s via Internet, tels que Whatsapp, Skype et FaceTime, sont bien s\u00fbr \u00e9galement possibles avec les cartes SIM pour Hawaii. Vous utiliserez alors le forfait de donn\u00e9es de la carte SIM. Vous pouvez continuer \u00e0 utiliser Whatsapp avec vos contacts, groupes et chats existants. Apr\u00e8s avoir ins\u00e9r\u00e9 une carte SIM pr\u00e9pay\u00e9e, Whatsapp peut vous demander si vous souhaitez cr\u00e9er une nouvelle identit\u00e9 ou si tout doit rester tel quel. Si c'est le cas, choisissez la deuxi\u00e8me option et rien ne changera. Vous pourrez ensuite continuer \u00e0 envoyer des messages et \u00e0 passer des appels avec Whatsapp comme d'habitude. <\/span>\r\n<h2><span data-contrast=\"\u00ab\">Couverture r\u00e9seau \u00e0 Hawaii<\/span><\/h2>\r\n<span data-contrast=\"\u00ab\">La couverture des r\u00e9seaux cellulaires est g\u00e9n\u00e9ralement excellente \u00e0 Hawa\u00ef. C'est particuli\u00e8rement vrai dans la capitale, Honolulu. La couverture sera moindre dans les zones naturelles recul\u00e9es. Sinon, la couverture est bonne dans les villes avec des cartes SIM hawa\u00efennes.<\/span>\r\n<h2><span lang=\"FR-FR\">Livraison gratuite \u00e0 domicile<\/span><\/h2>\r\nLa carte SIM Hawa\u00ef peut \u00eatre livr\u00e9e gratuitement \u00e0 votre domicile en France, en Belgique, au Luxembourg et en Suisse. Si vous commandez un jour ouvrable avant 14 heures, nous exp\u00e9dions votre commande le jour m\u00eame par la poste. Normalement, la livraison a lieu dans un d\u00e9lai de deux ou trois jours ouvrables. Avez-vous besoin d\u2019une livraison plus rapide? Alors, choisissez l\u2019eSIM, qui vous sera envoy\u00e9e par e-mail.","product_specificaties":"&nbsp;\r\n<h2><span data-contrast=\"\u00ab\">Advantages SIM card Hawaii<\/span><\/h2>\r\n<span data-contrast=\"\u00ab\">La carte SIM est disponible dans toutes les tailles (mini, micro et nano) et s'adapte \u00e0 tous les t\u00e9l\u00e9phones.<\/span>\r\n\r\n<span data-contrast=\"\u00ab\">La carte SIM Hawaii convient aux hotspots et aux appareils MIFI.<\/span>\r\n<h2><span data-contrast=\"\u00ab\">Data &amp; calling in Hawaii<\/span><\/h2>\r\n<span data-contrast=\"\u00ab\">Il existe deux variantes de la carte SIM Hawaii :<\/span>\r\n\r\n<span data-contrast=\"\u00ab\">12GB de donn\u00e9es \u20ac36<\/span>\r\n\r\n<span data-contrast=\"\u00ab\">12GB de donn\u00e9es inclus<\/span>\r\n\r\n<span data-contrast=\"\u00ab\">Donn\u00e9es illimit\u00e9es \u20ac 69,= *<\/span>\r\n\r\n<span data-contrast=\"\u00ab\">Incl. Donn\u00e9es illimit\u00e9es *<\/span>\r\n\r\nIncl. Appels illimit\u00e9s vers les num\u00e9ros locaux \u00e0 Hawa\u00ef\r\n\r\n<span data-contrast=\"\u00ab\">Les forfaits de donn\u00e9es sont valables pendant 30 jours apr\u00e8s l'activation.<\/span>\r\n\r\n<span data-contrast=\"\u00ab\">(*) Il existe une politique d'utilisation \u00e9quitable. <\/span><span data-contrast=\"\u00ab\">En cas d'utilisation extr\u00eame des donn\u00e9es ou de comportement d'appel excessif, le fournisseur aux \u00c9tats-Unis peut limiter les capacit\u00e9s de la carte SIM.<\/span>\r\n\r\n&nbsp;","product_handleiding":"&nbsp;\r\n<h2><span data-contrast=\"\u00ab\">Comment installer la carte SIM d'Hawa\u00ef dans mon t\u00e9l\u00e9phone ?<\/span><\/h2>\r\n<span data-contrast=\"\u00ab\">Ouvrez le coulissant sur le c\u00f4t\u00e9 du t\u00e9l\u00e9phone. Vous pouvez le faire avec la goupille fournie avec le t\u00e9l\u00e9phone. Si vous ne l'avez pas, vous pouvez en fabriquer une en pliant un trombone. Les cartes SIM Airport Telecom sont \u00e9galement livr\u00e9es avec une goupille suppl\u00e9mentaire.<\/span>\r\n\r\n<span data-contrast=\"\u00ab\">Retirez votre propre carte SIM et conservez-la en lieu s\u00fbr ! Ins\u00e9rez maintenant la nouvelle carte SIM. Il n'y a qu'une seule fa\u00e7on de le faire. Il se peut que votre t\u00e9l\u00e9phone puisse contenir plus d'une carte SIM. Ins\u00e9rez la nouvelle carte SIM en tant que carte suppl\u00e9mentaire.<\/span>\r\n\r\n<span data-contrast=\"\u00ab\">Repoussez maintenant la glissi\u00e8re de la carte SIM dans le t\u00e9l\u00e9phone. Si tout se passe bien, vous pouvez maintenant utiliser automatiquement la nouvelle carte SIM. Le t\u00e9l\u00e9phone peut vous demander de proc\u00e9der \u00e0 des r\u00e9glages suppl\u00e9mentaires.<\/span>\r\n\r\n&nbsp;","product_veelgestelde_vragen":[{"vraag":"Quelle carte SIM utiliser \u00e0 Hawaii ?","antwoord":"Pour un court s\u00e9jour de quelques jours, vous n'aurez probablement pas besoin d'autant de donn\u00e9es. Le forfait de 12GB de donn\u00e9es pour Hawa\u00ef peut alors suffire. Les applications comme Whatsapp, Instagram et la navigation ne consomment pas beaucoup de donn\u00e9es. Si vous restez plus longtemps, il peut \u00eatre utile de choisir l'option Illimit\u00e9 pour disposer de plus de donn\u00e9es.  "},{"vraag":"O\u00f9 acheter une carte SIM pour Hawaii ?","antwoord":"Achetez une carte SIM pour Hawaii aupr\u00e8s de Airport Telecom Schiphol. Vous pouvez la retirer dans le magasin. Ou commandez en ligne et la carte SIM sera livr\u00e9e gratuitement \u00e0 votre domicile."}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.4 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Carte SIM Hawa\u00ef achat d&#039;appels et d&#039;Internet pr\u00e9pay\u00e9s (illimit\u00e9s) - Airport Telecom FR<\/title>\n<meta name=\"description\" content=\"Recherche carte pr\u00e9pay\u00e9e Carte SIM Hawa\u00ef pour les appels (illimit\u00e9s) et Internet ? Accessible de mani\u00e8re optimale lors de d\u00e9placements en Carte SIM Australie et Oc\u00e9anie. Maintenant en vente chez !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/airporttelecom.com\/fr\/carte-sim\/hawai\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carte SIM Hawa\u00ef\" \/>\n<meta property=\"og:description\" content=\"Recherche carte pr\u00e9pay\u00e9e Carte SIM Hawa\u00ef pour les appels (illimit\u00e9s) et Internet ? Accessible de mani\u00e8re optimale lors de d\u00e9placements en Carte SIM Australie et Oc\u00e9anie. Maintenant en vente chez !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/airporttelecom.com\/fr\/carte-sim\/hawai\/\" \/>\n<meta property=\"og:site_name\" content=\"Airport Telecom FR\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-28T09:02:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/airporttelecom.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/07\/Simkaart-Hawaii.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"319\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/carte-sim\\\/hawai\\\/\",\"url\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/carte-sim\\\/hawai\\\/\",\"name\":\"Carte SIM Hawa\u00ef achat d'appels et d'Internet pr\u00e9pay\u00e9s (illimit\u00e9s) - Airport Telecom FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/carte-sim\\\/hawai\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/carte-sim\\\/hawai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/07\\\/Simkaart-Hawaii.png\",\"datePublished\":\"2024-07-30T09:05:23+00:00\",\"dateModified\":\"2026-08-28T09:02:05+00:00\",\"description\":\"Recherche carte pr\u00e9pay\u00e9e Carte SIM Hawa\u00ef pour les appels (illimit\u00e9s) et Internet ? Accessible de mani\u00e8re optimale lors de d\u00e9placements en Carte SIM Australie et Oc\u00e9anie. Maintenant en vente chez !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/carte-sim\\\/hawai\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/carte-sim\\\/hawai\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/carte-sim\\\/hawai\\\/#primaryimage\",\"url\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/07\\\/Simkaart-Hawaii.png\",\"contentUrl\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/07\\\/Simkaart-Hawaii.png\",\"width\":800,\"height\":319,\"caption\":\"Carte Sim Hawaii\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/carte-sim\\\/hawai\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carte SIM\",\"item\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/carte-sim\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Carte SIM Hawa\u00ef\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/\",\"name\":\"Airport Telecom\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/#organization\",\"name\":\"Airport Telecom\",\"url\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/06\\\/icon.png?wsr\",\"contentUrl\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/06\\\/icon.png?wsr\",\"width\":110,\"height\":110,\"caption\":\"Airport Telecom\"},\"image\":{\"@id\":\"https:\\\/\\\/airporttelecom.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Carte SIM Hawa\u00ef achat d'appels et d'Internet pr\u00e9pay\u00e9s (illimit\u00e9s) - Airport Telecom FR","description":"Recherche carte pr\u00e9pay\u00e9e Carte SIM Hawa\u00ef pour les appels (illimit\u00e9s) et Internet ? Accessible de mani\u00e8re optimale lors de d\u00e9placements en Carte SIM Australie et Oc\u00e9anie. Maintenant en vente chez !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/airporttelecom.com\/fr\/carte-sim\/hawai\/","og_locale":"fr_FR","og_type":"article","og_title":"Carte SIM Hawa\u00ef","og_description":"Recherche carte pr\u00e9pay\u00e9e Carte SIM Hawa\u00ef pour les appels (illimit\u00e9s) et Internet ? Accessible de mani\u00e8re optimale lors de d\u00e9placements en Carte SIM Australie et Oc\u00e9anie. Maintenant en vente chez !","og_url":"https:\/\/airporttelecom.com\/fr\/carte-sim\/hawai\/","og_site_name":"Airport Telecom FR","article_modified_time":"2026-08-28T09:02:05+00:00","og_image":[{"width":800,"height":319,"url":"https:\/\/airporttelecom.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/07\/Simkaart-Hawaii.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/airporttelecom.com\/fr\/carte-sim\/hawai\/","url":"https:\/\/airporttelecom.com\/fr\/carte-sim\/hawai\/","name":"Carte SIM Hawa\u00ef achat d'appels et d'Internet pr\u00e9pay\u00e9s (illimit\u00e9s) - Airport Telecom FR","isPartOf":{"@id":"https:\/\/airporttelecom.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/airporttelecom.com\/fr\/carte-sim\/hawai\/#primaryimage"},"image":{"@id":"https:\/\/airporttelecom.com\/fr\/carte-sim\/hawai\/#primaryimage"},"thumbnailUrl":"https:\/\/airporttelecom.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/07\/Simkaart-Hawaii.png","datePublished":"2024-07-30T09:05:23+00:00","dateModified":"2026-08-28T09:02:05+00:00","description":"Recherche carte pr\u00e9pay\u00e9e Carte SIM Hawa\u00ef pour les appels (illimit\u00e9s) et Internet ? Accessible de mani\u00e8re optimale lors de d\u00e9placements en Carte SIM Australie et Oc\u00e9anie. Maintenant en vente chez !","breadcrumb":{"@id":"https:\/\/airporttelecom.com\/fr\/carte-sim\/hawai\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/airporttelecom.com\/fr\/carte-sim\/hawai\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/airporttelecom.com\/fr\/carte-sim\/hawai\/#primaryimage","url":"https:\/\/airporttelecom.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/07\/Simkaart-Hawaii.png","contentUrl":"https:\/\/airporttelecom.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/07\/Simkaart-Hawaii.png","width":800,"height":319,"caption":"Carte Sim Hawaii"},{"@type":"BreadcrumbList","@id":"https:\/\/airporttelecom.com\/fr\/carte-sim\/hawai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/airporttelecom.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Carte SIM","item":"https:\/\/airporttelecom.com\/fr\/carte-sim\/"},{"@type":"ListItem","position":3,"name":"Carte SIM Hawa\u00ef"}]},{"@type":"WebSite","@id":"https:\/\/airporttelecom.com\/fr\/#website","url":"https:\/\/airporttelecom.com\/fr\/","name":"Airport Telecom","description":"","publisher":{"@id":"https:\/\/airporttelecom.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/airporttelecom.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/airporttelecom.com\/fr\/#organization","name":"Airport Telecom","url":"https:\/\/airporttelecom.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/airporttelecom.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/airporttelecom.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/icon.png?wsr","contentUrl":"https:\/\/airporttelecom.com\/fr\/wp-content\/uploads\/sites\/5\/2024\/06\/icon.png?wsr","width":110,"height":110,"caption":"Airport Telecom"},"image":{"@id":"https:\/\/airporttelecom.com\/fr\/#\/schema\/logo\/image\/"}}]}},"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/airporttelecom.com\/fr\/wp-json\/wp\/v2\/product\/755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/airporttelecom.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/airporttelecom.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/airporttelecom.com\/fr\/wp-json\/wp\/v2\/comments?post=755"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/airporttelecom.com\/fr\/wp-json\/wp\/v2\/media\/1157"}],"wp:attachment":[{"href":"https:\/\/airporttelecom.com\/fr\/wp-json\/wp\/v2\/media?parent=755"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/airporttelecom.com\/fr\/wp-json\/wp\/v2\/product_brand?post=755"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/airporttelecom.com\/fr\/wp-json\/wp\/v2\/product_cat?post=755"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/airporttelecom.com\/fr\/wp-json\/wp\/v2\/product_tag?post=755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}